{"id":63,"count":0,"description":"","link":"https:\/\/levellab.ee\/en\/portfolio-category\/year\/","name":"Year","slug":"year","taxonomy":"portfolio_category","parent":0,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/levellab.ee\/en\/wp-json\/wp\/v2\/portfolio_category\/63","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/levellab.ee\/en\/wp-json\/wp\/v2\/portfolio_category"}],"about":[{"href":"https:\/\/levellab.ee\/en\/wp-json\/wp\/v2\/taxonomies\/portfolio_category"}],"wp:post_type":[{"href":"https:\/\/levellab.ee\/en\/wp-json\/wp\/v2\/portfolio?portfolio_category=63"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}